{"id":245339,"date":"2024-07-04T02:52:39","date_gmt":"2024-07-04T02:52:39","guid":{"rendered":"https:\/\/web05-hveudngpgzf9hyf7.southeastasia-01.azurewebsites.net\/shop\/uncategorized\/%e0%b8%95%e0%b8%b9%e0%b9%89%e0%b8%9f%e0%b8%b1%e0%b8%81%e0%b9%84%e0%b8%82%e0%b9%88%e0%b9%81%e0%b8%9a%e0%b8%9a%e0%b8%ad%e0%b9%80%e0%b8%99%e0%b8%81%e0%b8%9b%e0%b8%a3%e0%b8%b"},"modified":"2024-07-04T02:52:39","modified_gmt":"2024-07-04T02:52:39","slug":"%e0%b8%95%e0%b8%b9%e0%b9%89%e0%b8%9f%e0%b8%b1%e0%b8%81%e0%b9%84%e0%b8%82%e0%b9%88%e0%b9%81%e0%b8%9a%e0%b8%9a%e0%b8%ad%e0%b9%80%e0%b8%99%e0%b8%81%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%aa%e0%b8%87%e0%b8%84","status":"publish","type":"product","link":"https:\/\/www.douyeebiomed.com\/th\/\u0e23\u0e49\u0e32\u0e19\u0e04\u0e49\u0e32\/%e0%b8%ad%e0%b8%b8%e0%b8%9b%e0%b8%81%e0%b8%a3%e0%b8%93%e0%b9%8c%e0%b8%ab%e0%b9%89%e0%b8%ad%e0%b8%87%e0%b8%9b%e0%b8%8f%e0%b8%b4%e0%b8%9a%e0%b8%b1%e0%b8%95%e0%b8%b4%e0%b8%81%e0%b8%b2%e0%b8%a3\/%e0%b8%95%e0%b8%b9%e0%b9%89%e0%b8%9f%e0%b8%b1%e0%b8%81%e0%b9%84%e0%b8%82%e0%b9%88%e0%b9%83%e0%b8%99%e0%b8%ab%e0%b9%89%e0%b8%ad%e0%b8%87%e0%b8%9b%e0%b8%8f%e0%b8%b4%e0%b8%9a%e0%b8%b1%e0%b8%95%e0%b8%b4\/%e0%b8%95%e0%b8%b9%e0%b9%89%e0%b8%9f%e0%b8%b1%e0%b8%81%e0%b9%84%e0%b8%82%e0%b9%88%e0%b9%81%e0%b8%9a%e0%b8%9a%e0%b8%ad%e0%b9%80%e0%b8%99%e0%b8%81%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%aa%e0%b8%87%e0%b8%84\/","title":{"rendered":"\u0e15\u0e39\u0e49\u0e1f\u0e31\u0e01\u0e44\u0e02\u0e48\u0e41\u0e1a\u0e1a\u0e2d\u0e40\u0e19\u0e01\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c\u0e43\u0e19\u0e2b\u0e49\u0e2d\u0e07\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19: \u0e01\u0e32\u0e23\u0e40\u0e01\u0e47\u0e1a\u0e23\u0e31\u0e01\u0e29\u0e32\u0e22\u0e32 \u0e2a\u0e32\u0e23\u0e40\u0e04\u0e21\u0e35 \u0e27\u0e31\u0e04\u0e0b\u0e35\u0e19 \u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19\u0e2a\u0e32\u0e23\u0e44\u0e14\u0e2d\u0e30\u0e44\u0e25\u0e40\u0e2a\u0e17 \u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19\u0e19\u0e49\u0e33\u0e40\u0e01\u0e25\u0e37\u0e2d\u0e17\u0e32\u0e07\u0e2a\u0e23\u0e35\u0e23\u0e27\u0e34\u0e17\u0e22\u0e32 \u0e01\u0e32\u0e23\u0e40\u0e01\u0e47\u0e1a\u0e23\u0e31\u0e01\u0e29\u0e32\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e40\u0e01\u0e47\u0e1a\u0e23\u0e31\u0e01\u0e29\u0e32\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c\u0e43\u0e19\u0e2b\u0e49\u0e2d\u0e07\u0e1c\u0e48\u0e32\u0e15\u0e31\u0e14 \u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19\u0e19\u0e49\u0e33\u0e40\u0e01\u0e25\u0e37\u0e2d\u0e18\u0e23\u0e23\u0e21\u0e14\u0e32 35-37 \u0e2d\u0e07\u0e28\u0e32\u0e40\u0e0b\u0e25\u0e40\u0e0b\u0e35\u0e22\u0e2a \u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19\u0e41\u0e21\u0e19\u0e19\u0e34\u0e17\u0e2d\u0e25 37-42 \u0e2d\u0e07\u0e28\u0e32\u0e40\u0e0b\u0e25\u0e40\u0e0b\u0e35\u0e22\u0e2a \u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19\u0e02\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e27\u0e2d\u0e31\u0e25\u0e15\u0e23\u0e32\u0e42\u0e0b\u0e19\u0e34\u0e04 B \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e49\u0e19   <\/p>\n<p>\u0e23\u0e38\u0e48\u0e19: 100 \/ 150 \/ 200 \/ 300<br \/>\n \u0e04\u0e27\u0e32\u0e21\u0e08\u0e38: 100L \/150L \/ 200L \/ 300L<\/p>\n<p>\u0e04\u0e38\u0e13\u0e2a\u0e21\u0e1a\u0e31\u0e15\u0e34:<br \/>\n &#8211; \u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e17\u0e48\u0e2d\u0e25\u0e21\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e2d\u0e01\u0e25\u0e31\u0e01\u0e29\u0e13\u0e4c\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e21\u0e35\u0e2d\u0e38\u0e13\u0e2b\u0e20\u0e39\u0e21\u0e34\u0e2a\u0e21\u0e48\u0e33\u0e40\u0e2a\u0e21\u0e2d\u0e21\u0e32\u0e01\u0e02\u0e36\u0e49\u0e19<br \/>\n &#8211; \u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e15\u0e31\u0e27\u0e41\u0e22\u0e01\u0e41\u0e1a\u0e1a\u0e01\u0e31\u0e19\u0e25\u0e37\u0e48\u0e19\u0e0a\u0e48\u0e27\u0e22\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e44\u0e21\u0e48\u0e43\u0e2b\u0e49\u0e15\u0e31\u0e27\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2b\u0e25\u0e38\u0e14\u0e2d\u0e2d\u0e01\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e14\u0e36\u0e07\u0e0a\u0e31\u0e49\u0e19\u0e27\u0e32\u0e07<br \/>\n &#8211; \u0e2b\u0e19\u0e49\u0e32\u0e08\u0e2d\u0e2a\u0e31\u0e21\u0e1c\u0e31\u0e2a LCD \u0e2a\u0e35\u0e02\u0e19\u0e32\u0e14 7 \u0e19\u0e34\u0e49\u0e27 \u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a\u0e01\u0e23\u0e32\u0e1f\u0e2d\u0e38\u0e13\u0e2b\u0e20\u0e39\u0e21\u0e34\u0e41\u0e1a\u0e1a\u0e40\u0e23\u0e35\u0e22\u0e25\u0e44\u0e17\u0e21\u0e4c \u0e2d\u0e34\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e40\u0e1f\u0e0b\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e41\u0e1a\u0e1a\u0e40\u0e21\u0e19\u0e39\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e07\u0e48\u0e32\u0e22\u0e41\u0e25\u0e30\u0e40\u0e02\u0e49\u0e32\u0e43\u0e08\u0e07\u0e48\u0e32\u0e22 \u0e2a\u0e30\u0e14\u0e27\u0e01\u0e15\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e2a\u0e31\u0e07\u0e40\u0e01\u0e15\u0e41\u0e25\u0e30\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19<br \/>\n &#8211; \u0e2d\u0e33\u0e19\u0e32\u0e08\u0e2d\u0e34\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e40\u0e1f\u0e0b\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e07\u0e32\u0e19 3 \u0e23\u0e30\u0e14\u0e31\u0e1a (\u0e1c\u0e39\u0e49\u0e14\u0e39\u0e41\u0e25\u0e23\u0e30\u0e1a\u0e1a \u0e1c\u0e39\u0e49\u0e17\u0e14\u0e25\u0e2d\u0e07 \u0e1c\u0e39\u0e49\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e07\u0e32\u0e19) \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e44\u0e21\u0e48\u0e43\u0e2b\u0e49\u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23\u0e17\u0e35\u0e48\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e01\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e40\u0e01\u0e34\u0e14\u0e01\u0e32\u0e23\u0e2b\u0e22\u0e38\u0e14\u0e0a\u0e30\u0e07\u0e31\u0e01\u0e43\u0e19\u0e01\u0e32\u0e23\u0e17\u0e14\u0e2a\u0e2d\u0e1a\u0e2b\u0e23\u0e37\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e25\u0e49\u0e21\u0e40\u0e2b\u0e25\u0e27\u0e02\u0e2d\u0e07\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c<br \/>\n &#8211; \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e2d\u0e34\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e40\u0e1f\u0e0b\u0e1e\u0e35\u0e0b\u0e35\u0e17\u0e35\u0e48\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e15\u0e48\u0e2d\u0e01\u0e31\u0e19\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19\u0e23\u0e30\u0e22\u0e30\u0e44\u0e01\u0e25\u0e41\u0e25\u0e30\u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e41\u0e2d\u0e1b\u0e42\u0e17\u0e23\u0e28\u0e31\u0e1e\u0e17\u0e4c\u0e21\u0e37\u0e2d\u0e16\u0e37\u0e2d\u0e40\u0e2a\u0e23\u0e34\u0e21 <\/p>\n<p>\u0e25\u0e07\u0e17\u0e30\u0e40\u0e1a\u0e35\u0e22\u0e19\u0e17\u0e35\u0e48\u0e2d\u0e22\u0e39\u0e48\u0e2d\u0e35\u0e40\u0e21\u0e25\u0e2b\u0e23\u0e37\u0e2d\u0e15\u0e34\u0e14\u0e15\u0e48\u0e2d\u0e40\u0e23\u0e32\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e23\u0e31\u0e1a\u0e23\u0e32\u0e22\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e08\u0e33\u0e40\u0e1e\u0e32\u0e30<\/p>\n","protected":false},"featured_media":243084,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":""},"product_cat":[282],"product_tag":[],"class_list":["post-245339","product","type-product","status-publish","has-post-thumbnail","hentry","product_cat-282"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u0e15\u0e39\u0e49\u0e1f\u0e31\u0e01\u0e44\u0e02\u0e48\u0e41\u0e1a\u0e1a\u0e2d\u0e40\u0e19\u0e01\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c\u0e43\u0e19\u0e2b\u0e49\u0e2d\u0e07\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23 - \u0e42\u0e14\u0e48\u0e27\u0e22\u0e35\u0e48<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/douyeebiomed.com\/th\/\u0e23\u0e49\u0e32\u0e19\u0e04\u0e49\u0e32\/\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2b\u0e49\u0e2d\u0e07\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23\/\u0e15\u0e39\u0e49\u0e1f\u0e31\u0e01\u0e44\u0e02\u0e48\u0e43\u0e19\u0e2b\u0e49\u0e2d\u0e07\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\/\u0e15\u0e39\u0e49\u0e1f\u0e31\u0e01\u0e44\u0e02\u0e48\u0e41\u0e1a\u0e1a\u0e2d\u0e40\u0e19\u0e01\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\/\" \/>\n<meta property=\"og:locale\" content=\"th_TH\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0e15\u0e39\u0e49\u0e1f\u0e31\u0e01\u0e44\u0e02\u0e48\u0e41\u0e1a\u0e1a\u0e2d\u0e40\u0e19\u0e01\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c\u0e43\u0e19\u0e2b\u0e49\u0e2d\u0e07\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23 - \u0e42\u0e14\u0e48\u0e27\u0e22\u0e35\u0e48\" \/>\n<meta property=\"og:description\" content=\"\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19: \u0e01\u0e32\u0e23\u0e40\u0e01\u0e47\u0e1a\u0e23\u0e31\u0e01\u0e29\u0e32\u0e22\u0e32 \u0e2a\u0e32\u0e23\u0e40\u0e04\u0e21\u0e35 \u0e27\u0e31\u0e04\u0e0b\u0e35\u0e19 \u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19\u0e2a\u0e32\u0e23\u0e44\u0e14\u0e2d\u0e30\u0e44\u0e25\u0e40\u0e2a\u0e17 \u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19\u0e19\u0e49\u0e33\u0e40\u0e01\u0e25\u0e37\u0e2d\u0e17\u0e32\u0e07\u0e2a\u0e23\u0e35\u0e23\u0e27\u0e34\u0e17\u0e22\u0e32 \u0e01\u0e32\u0e23\u0e40\u0e01\u0e47\u0e1a\u0e23\u0e31\u0e01\u0e29\u0e32\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e40\u0e01\u0e47\u0e1a\u0e23\u0e31\u0e01\u0e29\u0e32\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c\u0e43\u0e19\u0e2b\u0e49\u0e2d\u0e07\u0e1c\u0e48\u0e32\u0e15\u0e31\u0e14 \u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19\u0e19\u0e49\u0e33\u0e40\u0e01\u0e25\u0e37\u0e2d\u0e18\u0e23\u0e23\u0e21\u0e14\u0e32 35-37 \u0e2d\u0e07\u0e28\u0e32\u0e40\u0e0b\u0e25\u0e40\u0e0b\u0e35\u0e22\u0e2a \u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19\u0e41\u0e21\u0e19\u0e19\u0e34\u0e17\u0e2d\u0e25 37-42 \u0e2d\u0e07\u0e28\u0e32\u0e40\u0e0b\u0e25\u0e40\u0e0b\u0e35\u0e22\u0e2a \u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19\u0e02\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e27\u0e2d\u0e31\u0e25\u0e15\u0e23\u0e32\u0e42\u0e0b\u0e19\u0e34\u0e04 B \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e49\u0e19   \u0e23\u0e38\u0e48\u0e19: 100 \/ 150 \/ 200 \/ 300 \u0e04\u0e27\u0e32\u0e21\u0e08\u0e38: 100L \/150L \/ 200L \/ 300L \u0e04\u0e38\u0e13\u0e2a\u0e21\u0e1a\u0e31\u0e15\u0e34: - \u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e17\u0e48\u0e2d\u0e25\u0e21\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e2d\u0e01\u0e25\u0e31\u0e01\u0e29\u0e13\u0e4c\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e21\u0e35\u0e2d\u0e38\u0e13\u0e2b\u0e20\u0e39\u0e21\u0e34\u0e2a\u0e21\u0e48\u0e33\u0e40\u0e2a\u0e21\u0e2d\u0e21\u0e32\u0e01\u0e02\u0e36\u0e49\u0e19 - \u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e15\u0e31\u0e27\u0e41\u0e22\u0e01\u0e41\u0e1a\u0e1a\u0e01\u0e31\u0e19\u0e25\u0e37\u0e48\u0e19\u0e0a\u0e48\u0e27\u0e22\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e44\u0e21\u0e48\u0e43\u0e2b\u0e49\u0e15\u0e31\u0e27\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2b\u0e25\u0e38\u0e14\u0e2d\u0e2d\u0e01\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e14\u0e36\u0e07\u0e0a\u0e31\u0e49\u0e19\u0e27\u0e32\u0e07 - \u0e2b\u0e19\u0e49\u0e32\u0e08\u0e2d\u0e2a\u0e31\u0e21\u0e1c\u0e31\u0e2a LCD \u0e2a\u0e35\u0e02\u0e19\u0e32\u0e14 7 \u0e19\u0e34\u0e49\u0e27 \u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a\u0e01\u0e23\u0e32\u0e1f\u0e2d\u0e38\u0e13\u0e2b\u0e20\u0e39\u0e21\u0e34\u0e41\u0e1a\u0e1a\u0e40\u0e23\u0e35\u0e22\u0e25\u0e44\u0e17\u0e21\u0e4c \u0e2d\u0e34\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e40\u0e1f\u0e0b\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e41\u0e1a\u0e1a\u0e40\u0e21\u0e19\u0e39\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e07\u0e48\u0e32\u0e22\u0e41\u0e25\u0e30\u0e40\u0e02\u0e49\u0e32\u0e43\u0e08\u0e07\u0e48\u0e32\u0e22 \u0e2a\u0e30\u0e14\u0e27\u0e01\u0e15\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e2a\u0e31\u0e07\u0e40\u0e01\u0e15\u0e41\u0e25\u0e30\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19 - \u0e2d\u0e33\u0e19\u0e32\u0e08\u0e2d\u0e34\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e40\u0e1f\u0e0b\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e07\u0e32\u0e19 3 \u0e23\u0e30\u0e14\u0e31\u0e1a (\u0e1c\u0e39\u0e49\u0e14\u0e39\u0e41\u0e25\u0e23\u0e30\u0e1a\u0e1a \u0e1c\u0e39\u0e49\u0e17\u0e14\u0e25\u0e2d\u0e07 \u0e1c\u0e39\u0e49\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e07\u0e32\u0e19) \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e44\u0e21\u0e48\u0e43\u0e2b\u0e49\u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23\u0e17\u0e35\u0e48\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e01\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e40\u0e01\u0e34\u0e14\u0e01\u0e32\u0e23\u0e2b\u0e22\u0e38\u0e14\u0e0a\u0e30\u0e07\u0e31\u0e01\u0e43\u0e19\u0e01\u0e32\u0e23\u0e17\u0e14\u0e2a\u0e2d\u0e1a\u0e2b\u0e23\u0e37\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e25\u0e49\u0e21\u0e40\u0e2b\u0e25\u0e27\u0e02\u0e2d\u0e07\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c - \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e2d\u0e34\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e40\u0e1f\u0e0b\u0e1e\u0e35\u0e0b\u0e35\u0e17\u0e35\u0e48\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e15\u0e48\u0e2d\u0e01\u0e31\u0e19\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19\u0e23\u0e30\u0e22\u0e30\u0e44\u0e01\u0e25\u0e41\u0e25\u0e30\u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e41\u0e2d\u0e1b\u0e42\u0e17\u0e23\u0e28\u0e31\u0e1e\u0e17\u0e4c\u0e21\u0e37\u0e2d\u0e16\u0e37\u0e2d\u0e40\u0e2a\u0e23\u0e34\u0e21  \u0e25\u0e07\u0e17\u0e30\u0e40\u0e1a\u0e35\u0e22\u0e19\u0e17\u0e35\u0e48\u0e2d\u0e22\u0e39\u0e48\u0e2d\u0e35\u0e40\u0e21\u0e25\u0e2b\u0e23\u0e37\u0e2d\u0e15\u0e34\u0e14\u0e15\u0e48\u0e2d\u0e40\u0e23\u0e32\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e23\u0e31\u0e1a\u0e23\u0e32\u0e22\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e08\u0e33\u0e40\u0e1e\u0e32\u0e30\" \/>\n<meta property=\"og:url\" content=\"https:\/\/douyeebiomed.com\/th\/\u0e23\u0e49\u0e32\u0e19\u0e04\u0e49\u0e32\/\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2b\u0e49\u0e2d\u0e07\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23\/\u0e15\u0e39\u0e49\u0e1f\u0e31\u0e01\u0e44\u0e02\u0e48\u0e43\u0e19\u0e2b\u0e49\u0e2d\u0e07\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\/\u0e15\u0e39\u0e49\u0e1f\u0e31\u0e01\u0e44\u0e02\u0e48\u0e41\u0e1a\u0e1a\u0e2d\u0e40\u0e19\u0e01\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\/\" \/>\n<meta property=\"og:site_name\" content=\"\u0e42\u0e14\u0e48\u0e27\u0e22\u0e35\u0e48\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.douyeebiomed.com\/wp-content\/uploads\/2024\/07\/706-BJPX-xxx-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/douyeebiomed.com\/th\/\u0e23\u0e49\u0e32\u0e19\u0e04\u0e49\u0e32\/%e0%b8%ad%e0%b8%b8%e0%b8%9b%e0%b8%81%e0%b8%a3%e0%b8%93%e0%b9%8c%e0%b8%ab%e0%b9%89%e0%b8%ad%e0%b8%87%e0%b8%9b%e0%b8%8f%e0%b8%b4%e0%b8%9a%e0%b8%b1%e0%b8%95%e0%b8%b4%e0%b8%81%e0%b8%b2%e0%b8%a3\/%e0%b8%95%e0%b8%b9%e0%b9%89%e0%b8%9f%e0%b8%b1%e0%b8%81%e0%b9%84%e0%b8%82%e0%b9%88%e0%b9%83%e0%b8%99%e0%b8%ab%e0%b9%89%e0%b8%ad%e0%b8%87%e0%b8%9b%e0%b8%8f%e0%b8%b4%e0%b8%9a%e0%b8%b1%e0%b8%95%e0%b8%b4\/%e0%b8%95%e0%b8%b9%e0%b9%89%e0%b8%9f%e0%b8%b1%e0%b8%81%e0%b9%84%e0%b8%82%e0%b9%88%e0%b9%81%e0%b8%9a%e0%b8%9a%e0%b8%ad%e0%b9%80%e0%b8%99%e0%b8%81%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%aa%e0%b8%87%e0%b8%84\/\",\"url\":\"https:\/\/douyeebiomed.com\/th\/\u0e23\u0e49\u0e32\u0e19\u0e04\u0e49\u0e32\/%e0%b8%ad%e0%b8%b8%e0%b8%9b%e0%b8%81%e0%b8%a3%e0%b8%93%e0%b9%8c%e0%b8%ab%e0%b9%89%e0%b8%ad%e0%b8%87%e0%b8%9b%e0%b8%8f%e0%b8%b4%e0%b8%9a%e0%b8%b1%e0%b8%95%e0%b8%b4%e0%b8%81%e0%b8%b2%e0%b8%a3\/%e0%b8%95%e0%b8%b9%e0%b9%89%e0%b8%9f%e0%b8%b1%e0%b8%81%e0%b9%84%e0%b8%82%e0%b9%88%e0%b9%83%e0%b8%99%e0%b8%ab%e0%b9%89%e0%b8%ad%e0%b8%87%e0%b8%9b%e0%b8%8f%e0%b8%b4%e0%b8%9a%e0%b8%b1%e0%b8%95%e0%b8%b4\/%e0%b8%95%e0%b8%b9%e0%b9%89%e0%b8%9f%e0%b8%b1%e0%b8%81%e0%b9%84%e0%b8%82%e0%b9%88%e0%b9%81%e0%b8%9a%e0%b8%9a%e0%b8%ad%e0%b9%80%e0%b8%99%e0%b8%81%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%aa%e0%b8%87%e0%b8%84\/\",\"name\":\"\u0e15\u0e39\u0e49\u0e1f\u0e31\u0e01\u0e44\u0e02\u0e48\u0e41\u0e1a\u0e1a\u0e2d\u0e40\u0e19\u0e01\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c\u0e43\u0e19\u0e2b\u0e49\u0e2d\u0e07\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23 - \u0e42\u0e14\u0e48\u0e27\u0e22\u0e35\u0e48\",\"isPartOf\":{\"@id\":\"https:\/\/web05-hveudngpgzf9hyf7.southeastasia-01.azurewebsites.net\/vi\/#website\"},\"datePublished\":\"2024-07-04T02:52:39+00:00\",\"dateModified\":\"2024-07-04T02:52:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/douyeebiomed.com\/th\/\u0e23\u0e49\u0e32\u0e19\u0e04\u0e49\u0e32\/%e0%b8%ad%e0%b8%b8%e0%b8%9b%e0%b8%81%e0%b8%a3%e0%b8%93%e0%b9%8c%e0%b8%ab%e0%b9%89%e0%b8%ad%e0%b8%87%e0%b8%9b%e0%b8%8f%e0%b8%b4%e0%b8%9a%e0%b8%b1%e0%b8%95%e0%b8%b4%e0%b8%81%e0%b8%b2%e0%b8%a3\/%e0%b8%95%e0%b8%b9%e0%b9%89%e0%b8%9f%e0%b8%b1%e0%b8%81%e0%b9%84%e0%b8%82%e0%b9%88%e0%b9%83%e0%b8%99%e0%b8%ab%e0%b9%89%e0%b8%ad%e0%b8%87%e0%b8%9b%e0%b8%8f%e0%b8%b4%e0%b8%9a%e0%b8%b1%e0%b8%95%e0%b8%b4\/%e0%b8%95%e0%b8%b9%e0%b9%89%e0%b8%9f%e0%b8%b1%e0%b8%81%e0%b9%84%e0%b8%82%e0%b9%88%e0%b9%81%e0%b8%9a%e0%b8%9a%e0%b8%ad%e0%b9%80%e0%b8%99%e0%b8%81%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%aa%e0%b8%87%e0%b8%84\/#breadcrumb\"},\"inLanguage\":\"th\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/douyeebiomed.com\/th\/\u0e23\u0e49\u0e32\u0e19\u0e04\u0e49\u0e32\/%e0%b8%ad%e0%b8%b8%e0%b8%9b%e0%b8%81%e0%b8%a3%e0%b8%93%e0%b9%8c%e0%b8%ab%e0%b9%89%e0%b8%ad%e0%b8%87%e0%b8%9b%e0%b8%8f%e0%b8%b4%e0%b8%9a%e0%b8%b1%e0%b8%95%e0%b8%b4%e0%b8%81%e0%b8%b2%e0%b8%a3\/%e0%b8%95%e0%b8%b9%e0%b9%89%e0%b8%9f%e0%b8%b1%e0%b8%81%e0%b9%84%e0%b8%82%e0%b9%88%e0%b9%83%e0%b8%99%e0%b8%ab%e0%b9%89%e0%b8%ad%e0%b8%87%e0%b8%9b%e0%b8%8f%e0%b8%b4%e0%b8%9a%e0%b8%b1%e0%b8%95%e0%b8%b4\/%e0%b8%95%e0%b8%b9%e0%b9%89%e0%b8%9f%e0%b8%b1%e0%b8%81%e0%b9%84%e0%b8%82%e0%b9%88%e0%b9%81%e0%b8%9a%e0%b8%9a%e0%b8%ad%e0%b9%80%e0%b8%99%e0%b8%81%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%aa%e0%b8%87%e0%b8%84\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/douyeebiomed.com\/th\/\u0e23\u0e49\u0e32\u0e19\u0e04\u0e49\u0e32\/%e0%b8%ad%e0%b8%b8%e0%b8%9b%e0%b8%81%e0%b8%a3%e0%b8%93%e0%b9%8c%e0%b8%ab%e0%b9%89%e0%b8%ad%e0%b8%87%e0%b8%9b%e0%b8%8f%e0%b8%b4%e0%b8%9a%e0%b8%b1%e0%b8%95%e0%b8%b4%e0%b8%81%e0%b8%b2%e0%b8%a3\/%e0%b8%95%e0%b8%b9%e0%b9%89%e0%b8%9f%e0%b8%b1%e0%b8%81%e0%b9%84%e0%b8%82%e0%b9%88%e0%b9%83%e0%b8%99%e0%b8%ab%e0%b9%89%e0%b8%ad%e0%b8%87%e0%b8%9b%e0%b8%8f%e0%b8%b4%e0%b8%9a%e0%b8%b1%e0%b8%95%e0%b8%b4\/%e0%b8%95%e0%b8%b9%e0%b9%89%e0%b8%9f%e0%b8%b1%e0%b8%81%e0%b9%84%e0%b8%82%e0%b9%88%e0%b9%81%e0%b8%9a%e0%b8%9a%e0%b8%ad%e0%b9%80%e0%b8%99%e0%b8%81%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%aa%e0%b8%87%e0%b8%84\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/web05-hveudngpgzf9hyf7.southeastasia-01.azurewebsites.net\/vi\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0e23\u0e49\u0e32\u0e19\u0e04\u0e49\u0e32\",\"item\":\"https:\/\/douyeebiomed.com\/th\/%e0%b8%a3%e0%b9%89%e0%b8%b2%e0%b8%99%e0%b8%84%e0%b9%89%e0%b8%b2\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u0e15\u0e39\u0e49\u0e1f\u0e31\u0e01\u0e44\u0e02\u0e48\u0e41\u0e1a\u0e1a\u0e2d\u0e40\u0e19\u0e01\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c\u0e43\u0e19\u0e2b\u0e49\u0e2d\u0e07\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/web05-hveudngpgzf9hyf7.southeastasia-01.azurewebsites.net\/vi\/#website\",\"url\":\"https:\/\/web05-hveudngpgzf9hyf7.southeastasia-01.azurewebsites.net\/vi\/\",\"name\":\"\u0e42\u0e14\u0e48\u0e27\u0e22\u0e35\u0e48\",\"description\":\"\u0e40\u0e27\u0e47\u0e1a\u0e44\u0e0b\u0e15\u0e4c\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 Dou Yee\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/web05-hveudngpgzf9hyf7.southeastasia-01.azurewebsites.net\/vi\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"th\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0e15\u0e39\u0e49\u0e1f\u0e31\u0e01\u0e44\u0e02\u0e48\u0e41\u0e1a\u0e1a\u0e2d\u0e40\u0e19\u0e01\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c\u0e43\u0e19\u0e2b\u0e49\u0e2d\u0e07\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23 - \u0e42\u0e14\u0e48\u0e27\u0e22\u0e35\u0e48","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/douyeebiomed.com\/th\/\u0e23\u0e49\u0e32\u0e19\u0e04\u0e49\u0e32\/\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2b\u0e49\u0e2d\u0e07\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23\/\u0e15\u0e39\u0e49\u0e1f\u0e31\u0e01\u0e44\u0e02\u0e48\u0e43\u0e19\u0e2b\u0e49\u0e2d\u0e07\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\/\u0e15\u0e39\u0e49\u0e1f\u0e31\u0e01\u0e44\u0e02\u0e48\u0e41\u0e1a\u0e1a\u0e2d\u0e40\u0e19\u0e01\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\/","og_locale":"th_TH","og_type":"article","og_title":"\u0e15\u0e39\u0e49\u0e1f\u0e31\u0e01\u0e44\u0e02\u0e48\u0e41\u0e1a\u0e1a\u0e2d\u0e40\u0e19\u0e01\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c\u0e43\u0e19\u0e2b\u0e49\u0e2d\u0e07\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23 - \u0e42\u0e14\u0e48\u0e27\u0e22\u0e35\u0e48","og_description":"\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19: \u0e01\u0e32\u0e23\u0e40\u0e01\u0e47\u0e1a\u0e23\u0e31\u0e01\u0e29\u0e32\u0e22\u0e32 \u0e2a\u0e32\u0e23\u0e40\u0e04\u0e21\u0e35 \u0e27\u0e31\u0e04\u0e0b\u0e35\u0e19 \u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19\u0e2a\u0e32\u0e23\u0e44\u0e14\u0e2d\u0e30\u0e44\u0e25\u0e40\u0e2a\u0e17 \u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19\u0e19\u0e49\u0e33\u0e40\u0e01\u0e25\u0e37\u0e2d\u0e17\u0e32\u0e07\u0e2a\u0e23\u0e35\u0e23\u0e27\u0e34\u0e17\u0e22\u0e32 \u0e01\u0e32\u0e23\u0e40\u0e01\u0e47\u0e1a\u0e23\u0e31\u0e01\u0e29\u0e32\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e40\u0e01\u0e47\u0e1a\u0e23\u0e31\u0e01\u0e29\u0e32\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c\u0e43\u0e19\u0e2b\u0e49\u0e2d\u0e07\u0e1c\u0e48\u0e32\u0e15\u0e31\u0e14 \u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19\u0e19\u0e49\u0e33\u0e40\u0e01\u0e25\u0e37\u0e2d\u0e18\u0e23\u0e23\u0e21\u0e14\u0e32 35-37 \u0e2d\u0e07\u0e28\u0e32\u0e40\u0e0b\u0e25\u0e40\u0e0b\u0e35\u0e22\u0e2a \u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19\u0e41\u0e21\u0e19\u0e19\u0e34\u0e17\u0e2d\u0e25 37-42 \u0e2d\u0e07\u0e28\u0e32\u0e40\u0e0b\u0e25\u0e40\u0e0b\u0e35\u0e22\u0e2a \u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19\u0e02\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e27\u0e2d\u0e31\u0e25\u0e15\u0e23\u0e32\u0e42\u0e0b\u0e19\u0e34\u0e04 B \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e49\u0e19   \u0e23\u0e38\u0e48\u0e19: 100 \/ 150 \/ 200 \/ 300 \u0e04\u0e27\u0e32\u0e21\u0e08\u0e38: 100L \/150L \/ 200L \/ 300L \u0e04\u0e38\u0e13\u0e2a\u0e21\u0e1a\u0e31\u0e15\u0e34: - \u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e17\u0e48\u0e2d\u0e25\u0e21\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e2d\u0e01\u0e25\u0e31\u0e01\u0e29\u0e13\u0e4c\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e21\u0e35\u0e2d\u0e38\u0e13\u0e2b\u0e20\u0e39\u0e21\u0e34\u0e2a\u0e21\u0e48\u0e33\u0e40\u0e2a\u0e21\u0e2d\u0e21\u0e32\u0e01\u0e02\u0e36\u0e49\u0e19 - \u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e15\u0e31\u0e27\u0e41\u0e22\u0e01\u0e41\u0e1a\u0e1a\u0e01\u0e31\u0e19\u0e25\u0e37\u0e48\u0e19\u0e0a\u0e48\u0e27\u0e22\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e44\u0e21\u0e48\u0e43\u0e2b\u0e49\u0e15\u0e31\u0e27\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2b\u0e25\u0e38\u0e14\u0e2d\u0e2d\u0e01\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e14\u0e36\u0e07\u0e0a\u0e31\u0e49\u0e19\u0e27\u0e32\u0e07 - \u0e2b\u0e19\u0e49\u0e32\u0e08\u0e2d\u0e2a\u0e31\u0e21\u0e1c\u0e31\u0e2a LCD \u0e2a\u0e35\u0e02\u0e19\u0e32\u0e14 7 \u0e19\u0e34\u0e49\u0e27 \u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a\u0e01\u0e23\u0e32\u0e1f\u0e2d\u0e38\u0e13\u0e2b\u0e20\u0e39\u0e21\u0e34\u0e41\u0e1a\u0e1a\u0e40\u0e23\u0e35\u0e22\u0e25\u0e44\u0e17\u0e21\u0e4c \u0e2d\u0e34\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e40\u0e1f\u0e0b\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e41\u0e1a\u0e1a\u0e40\u0e21\u0e19\u0e39\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e07\u0e48\u0e32\u0e22\u0e41\u0e25\u0e30\u0e40\u0e02\u0e49\u0e32\u0e43\u0e08\u0e07\u0e48\u0e32\u0e22 \u0e2a\u0e30\u0e14\u0e27\u0e01\u0e15\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e2a\u0e31\u0e07\u0e40\u0e01\u0e15\u0e41\u0e25\u0e30\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19 - \u0e2d\u0e33\u0e19\u0e32\u0e08\u0e2d\u0e34\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e40\u0e1f\u0e0b\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e07\u0e32\u0e19 3 \u0e23\u0e30\u0e14\u0e31\u0e1a (\u0e1c\u0e39\u0e49\u0e14\u0e39\u0e41\u0e25\u0e23\u0e30\u0e1a\u0e1a \u0e1c\u0e39\u0e49\u0e17\u0e14\u0e25\u0e2d\u0e07 \u0e1c\u0e39\u0e49\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e07\u0e32\u0e19) \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e44\u0e21\u0e48\u0e43\u0e2b\u0e49\u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23\u0e17\u0e35\u0e48\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e01\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e40\u0e01\u0e34\u0e14\u0e01\u0e32\u0e23\u0e2b\u0e22\u0e38\u0e14\u0e0a\u0e30\u0e07\u0e31\u0e01\u0e43\u0e19\u0e01\u0e32\u0e23\u0e17\u0e14\u0e2a\u0e2d\u0e1a\u0e2b\u0e23\u0e37\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e25\u0e49\u0e21\u0e40\u0e2b\u0e25\u0e27\u0e02\u0e2d\u0e07\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c - \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e2d\u0e34\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e40\u0e1f\u0e0b\u0e1e\u0e35\u0e0b\u0e35\u0e17\u0e35\u0e48\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e15\u0e48\u0e2d\u0e01\u0e31\u0e19\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19\u0e23\u0e30\u0e22\u0e30\u0e44\u0e01\u0e25\u0e41\u0e25\u0e30\u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e41\u0e2d\u0e1b\u0e42\u0e17\u0e23\u0e28\u0e31\u0e1e\u0e17\u0e4c\u0e21\u0e37\u0e2d\u0e16\u0e37\u0e2d\u0e40\u0e2a\u0e23\u0e34\u0e21  \u0e25\u0e07\u0e17\u0e30\u0e40\u0e1a\u0e35\u0e22\u0e19\u0e17\u0e35\u0e48\u0e2d\u0e22\u0e39\u0e48\u0e2d\u0e35\u0e40\u0e21\u0e25\u0e2b\u0e23\u0e37\u0e2d\u0e15\u0e34\u0e14\u0e15\u0e48\u0e2d\u0e40\u0e23\u0e32\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e23\u0e31\u0e1a\u0e23\u0e32\u0e22\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e08\u0e33\u0e40\u0e1e\u0e32\u0e30","og_url":"https:\/\/douyeebiomed.com\/th\/\u0e23\u0e49\u0e32\u0e19\u0e04\u0e49\u0e32\/\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2b\u0e49\u0e2d\u0e07\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23\/\u0e15\u0e39\u0e49\u0e1f\u0e31\u0e01\u0e44\u0e02\u0e48\u0e43\u0e19\u0e2b\u0e49\u0e2d\u0e07\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\/\u0e15\u0e39\u0e49\u0e1f\u0e31\u0e01\u0e44\u0e02\u0e48\u0e41\u0e1a\u0e1a\u0e2d\u0e40\u0e19\u0e01\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\/","og_site_name":"\u0e42\u0e14\u0e48\u0e27\u0e22\u0e35\u0e48","og_image":[{"width":1000,"height":1000,"url":"https:\/\/www.douyeebiomed.com\/wp-content\/uploads\/2024\/07\/706-BJPX-xxx-1.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/douyeebiomed.com\/th\/\u0e23\u0e49\u0e32\u0e19\u0e04\u0e49\u0e32\/%e0%b8%ad%e0%b8%b8%e0%b8%9b%e0%b8%81%e0%b8%a3%e0%b8%93%e0%b9%8c%e0%b8%ab%e0%b9%89%e0%b8%ad%e0%b8%87%e0%b8%9b%e0%b8%8f%e0%b8%b4%e0%b8%9a%e0%b8%b1%e0%b8%95%e0%b8%b4%e0%b8%81%e0%b8%b2%e0%b8%a3\/%e0%b8%95%e0%b8%b9%e0%b9%89%e0%b8%9f%e0%b8%b1%e0%b8%81%e0%b9%84%e0%b8%82%e0%b9%88%e0%b9%83%e0%b8%99%e0%b8%ab%e0%b9%89%e0%b8%ad%e0%b8%87%e0%b8%9b%e0%b8%8f%e0%b8%b4%e0%b8%9a%e0%b8%b1%e0%b8%95%e0%b8%b4\/%e0%b8%95%e0%b8%b9%e0%b9%89%e0%b8%9f%e0%b8%b1%e0%b8%81%e0%b9%84%e0%b8%82%e0%b9%88%e0%b9%81%e0%b8%9a%e0%b8%9a%e0%b8%ad%e0%b9%80%e0%b8%99%e0%b8%81%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%aa%e0%b8%87%e0%b8%84\/","url":"https:\/\/douyeebiomed.com\/th\/\u0e23\u0e49\u0e32\u0e19\u0e04\u0e49\u0e32\/%e0%b8%ad%e0%b8%b8%e0%b8%9b%e0%b8%81%e0%b8%a3%e0%b8%93%e0%b9%8c%e0%b8%ab%e0%b9%89%e0%b8%ad%e0%b8%87%e0%b8%9b%e0%b8%8f%e0%b8%b4%e0%b8%9a%e0%b8%b1%e0%b8%95%e0%b8%b4%e0%b8%81%e0%b8%b2%e0%b8%a3\/%e0%b8%95%e0%b8%b9%e0%b9%89%e0%b8%9f%e0%b8%b1%e0%b8%81%e0%b9%84%e0%b8%82%e0%b9%88%e0%b9%83%e0%b8%99%e0%b8%ab%e0%b9%89%e0%b8%ad%e0%b8%87%e0%b8%9b%e0%b8%8f%e0%b8%b4%e0%b8%9a%e0%b8%b1%e0%b8%95%e0%b8%b4\/%e0%b8%95%e0%b8%b9%e0%b9%89%e0%b8%9f%e0%b8%b1%e0%b8%81%e0%b9%84%e0%b8%82%e0%b9%88%e0%b9%81%e0%b8%9a%e0%b8%9a%e0%b8%ad%e0%b9%80%e0%b8%99%e0%b8%81%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%aa%e0%b8%87%e0%b8%84\/","name":"\u0e15\u0e39\u0e49\u0e1f\u0e31\u0e01\u0e44\u0e02\u0e48\u0e41\u0e1a\u0e1a\u0e2d\u0e40\u0e19\u0e01\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c\u0e43\u0e19\u0e2b\u0e49\u0e2d\u0e07\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23 - \u0e42\u0e14\u0e48\u0e27\u0e22\u0e35\u0e48","isPartOf":{"@id":"https:\/\/web05-hveudngpgzf9hyf7.southeastasia-01.azurewebsites.net\/vi\/#website"},"datePublished":"2024-07-04T02:52:39+00:00","dateModified":"2024-07-04T02:52:39+00:00","breadcrumb":{"@id":"https:\/\/douyeebiomed.com\/th\/\u0e23\u0e49\u0e32\u0e19\u0e04\u0e49\u0e32\/%e0%b8%ad%e0%b8%b8%e0%b8%9b%e0%b8%81%e0%b8%a3%e0%b8%93%e0%b9%8c%e0%b8%ab%e0%b9%89%e0%b8%ad%e0%b8%87%e0%b8%9b%e0%b8%8f%e0%b8%b4%e0%b8%9a%e0%b8%b1%e0%b8%95%e0%b8%b4%e0%b8%81%e0%b8%b2%e0%b8%a3\/%e0%b8%95%e0%b8%b9%e0%b9%89%e0%b8%9f%e0%b8%b1%e0%b8%81%e0%b9%84%e0%b8%82%e0%b9%88%e0%b9%83%e0%b8%99%e0%b8%ab%e0%b9%89%e0%b8%ad%e0%b8%87%e0%b8%9b%e0%b8%8f%e0%b8%b4%e0%b8%9a%e0%b8%b1%e0%b8%95%e0%b8%b4\/%e0%b8%95%e0%b8%b9%e0%b9%89%e0%b8%9f%e0%b8%b1%e0%b8%81%e0%b9%84%e0%b8%82%e0%b9%88%e0%b9%81%e0%b8%9a%e0%b8%9a%e0%b8%ad%e0%b9%80%e0%b8%99%e0%b8%81%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%aa%e0%b8%87%e0%b8%84\/#breadcrumb"},"inLanguage":"th","potentialAction":[{"@type":"ReadAction","target":["https:\/\/douyeebiomed.com\/th\/\u0e23\u0e49\u0e32\u0e19\u0e04\u0e49\u0e32\/%e0%b8%ad%e0%b8%b8%e0%b8%9b%e0%b8%81%e0%b8%a3%e0%b8%93%e0%b9%8c%e0%b8%ab%e0%b9%89%e0%b8%ad%e0%b8%87%e0%b8%9b%e0%b8%8f%e0%b8%b4%e0%b8%9a%e0%b8%b1%e0%b8%95%e0%b8%b4%e0%b8%81%e0%b8%b2%e0%b8%a3\/%e0%b8%95%e0%b8%b9%e0%b9%89%e0%b8%9f%e0%b8%b1%e0%b8%81%e0%b9%84%e0%b8%82%e0%b9%88%e0%b9%83%e0%b8%99%e0%b8%ab%e0%b9%89%e0%b8%ad%e0%b8%87%e0%b8%9b%e0%b8%8f%e0%b8%b4%e0%b8%9a%e0%b8%b1%e0%b8%95%e0%b8%b4\/%e0%b8%95%e0%b8%b9%e0%b9%89%e0%b8%9f%e0%b8%b1%e0%b8%81%e0%b9%84%e0%b8%82%e0%b9%88%e0%b9%81%e0%b8%9a%e0%b8%9a%e0%b8%ad%e0%b9%80%e0%b8%99%e0%b8%81%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%aa%e0%b8%87%e0%b8%84\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/douyeebiomed.com\/th\/\u0e23\u0e49\u0e32\u0e19\u0e04\u0e49\u0e32\/%e0%b8%ad%e0%b8%b8%e0%b8%9b%e0%b8%81%e0%b8%a3%e0%b8%93%e0%b9%8c%e0%b8%ab%e0%b9%89%e0%b8%ad%e0%b8%87%e0%b8%9b%e0%b8%8f%e0%b8%b4%e0%b8%9a%e0%b8%b1%e0%b8%95%e0%b8%b4%e0%b8%81%e0%b8%b2%e0%b8%a3\/%e0%b8%95%e0%b8%b9%e0%b9%89%e0%b8%9f%e0%b8%b1%e0%b8%81%e0%b9%84%e0%b8%82%e0%b9%88%e0%b9%83%e0%b8%99%e0%b8%ab%e0%b9%89%e0%b8%ad%e0%b8%87%e0%b8%9b%e0%b8%8f%e0%b8%b4%e0%b8%9a%e0%b8%b1%e0%b8%95%e0%b8%b4\/%e0%b8%95%e0%b8%b9%e0%b9%89%e0%b8%9f%e0%b8%b1%e0%b8%81%e0%b9%84%e0%b8%82%e0%b9%88%e0%b9%81%e0%b8%9a%e0%b8%9a%e0%b8%ad%e0%b9%80%e0%b8%99%e0%b8%81%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%aa%e0%b8%87%e0%b8%84\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/web05-hveudngpgzf9hyf7.southeastasia-01.azurewebsites.net\/vi\/"},{"@type":"ListItem","position":2,"name":"\u0e23\u0e49\u0e32\u0e19\u0e04\u0e49\u0e32","item":"https:\/\/douyeebiomed.com\/th\/%e0%b8%a3%e0%b9%89%e0%b8%b2%e0%b8%99%e0%b8%84%e0%b9%89%e0%b8%b2\/"},{"@type":"ListItem","position":3,"name":"\u0e15\u0e39\u0e49\u0e1f\u0e31\u0e01\u0e44\u0e02\u0e48\u0e41\u0e1a\u0e1a\u0e2d\u0e40\u0e19\u0e01\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c\u0e43\u0e19\u0e2b\u0e49\u0e2d\u0e07\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23"}]},{"@type":"WebSite","@id":"https:\/\/web05-hveudngpgzf9hyf7.southeastasia-01.azurewebsites.net\/vi\/#website","url":"https:\/\/web05-hveudngpgzf9hyf7.southeastasia-01.azurewebsites.net\/vi\/","name":"\u0e42\u0e14\u0e48\u0e27\u0e22\u0e35\u0e48","description":"\u0e40\u0e27\u0e47\u0e1a\u0e44\u0e0b\u0e15\u0e4c\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 Dou Yee","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/web05-hveudngpgzf9hyf7.southeastasia-01.azurewebsites.net\/vi\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"th"}]}},"_links":{"self":[{"href":"https:\/\/www.douyeebiomed.com\/th\/wp-json\/wp\/v2\/product\/245339","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.douyeebiomed.com\/th\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.douyeebiomed.com\/th\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.douyeebiomed.com\/th\/wp-json\/wp\/v2\/comments?post=245339"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.douyeebiomed.com\/th\/wp-json\/wp\/v2\/media\/243084"}],"wp:attachment":[{"href":"https:\/\/www.douyeebiomed.com\/th\/wp-json\/wp\/v2\/media?parent=245339"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.douyeebiomed.com\/th\/wp-json\/wp\/v2\/product_cat?post=245339"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.douyeebiomed.com\/th\/wp-json\/wp\/v2\/product_tag?post=245339"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}